{"id":10919,"date":"2015-09-05T00:00:24","date_gmt":"2015-09-04T23:00:24","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=10919"},"modified":"2019-01-24T19:22:06","modified_gmt":"2019-01-24T18:22:06","slug":"veranear-una-cuestion-muy-personal","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/","title":{"rendered":"Veranear: Una cuesti\u00f3n muy personal"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=SqTbTjDzPQs\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10921\" data-permalink=\"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/veranear\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?fit=504%2C369&amp;ssl=1\" data-orig-size=\"504,369\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Veranear\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?fit=504%2C369&amp;ssl=1\" class=\"aligncenter wp-image-10921\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?resize=429%2C314\" alt=\"Veranear\" width=\"429\" height=\"314\" srcset=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?w=504&amp;ssl=1 504w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?resize=300%2C220&amp;ssl=1 300w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/a><\/p>\n<p>Finaliza el <em>XV Campeonato del Mundo de Atletismo 2015<\/em> celebrado en Pek\u00edn (los he seguido todos desde el primero de Helsinki en 1983) y presenciando embelesado cada prueba, una vez m\u00e1s me pregunto que lleva a los competidores a darlo todo hasta el final con independencia de las posibilidades de cada cual para ganar. Es cierto que la respuesta no se me hace mucho esperar pues en mi propia experiencia encuentro siempre la clave de un comportamiento que, m\u00e1s all\u00e1 del triunfo ante los dem\u00e1s, busca la superaci\u00f3n personal.<\/p>\n<p>Tras completar el pasado 13 de Junio <a href=\"https:\/\/drive.google.com\/file\/d\/0B5XVd3PlCrPZSzh1QUl6S2Iza1k\/edit\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Marathon-15<\/span>%<\/a>, sin dudar el mayor logro deportivo de mi vida, todo apuntaba a que el verano me regalar\u00eda un merecido descanso en pago justo al finalmente conseguido r\u00e9cord mundial. La \u00edntima percepci\u00f3n del \u00e9xito como certificado m\u00e1s que notarial del deber cumplido amansaba mi conciencia y justificaba una incontestable tregua en los \u00faltimos cuarenta a\u00f1os de mi rutina vital.<\/p>\n<p>Mis agostos en Segovia finalizaban siempre con la subida corriendo desde su Plaza Mayor hasta el Alto de Navacerrada, llegando el a\u00f1o pasado m\u00e1s all\u00e1, hasta la <span style=\"text-decoration: underline;\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Bola_del_Mundo\" target=\"_blank\" rel=\"noopener\">Bola del Mundo<\/a><\/span> (32 kms. de subida constante hasta los 2.275 m.), como inicio de mi preparaci\u00f3n para <span style=\"text-decoration: underline;\"><a href=\"https:\/\/docs.google.com\/file\/d\/0B5XVd3PlCrPZLS1oclliSVlJWVE\/edit\" target=\"_blank\" rel=\"noopener\">Marathon-15%<\/a><\/span>. El presente pod\u00eda romper la tradici\u00f3n y con seguridad nadie me lo iba a reprochar. Nadie\u2026 excepto yo.<\/p>\n<p>A mis 54 a\u00f1os es evidente que nunca me encontrar\u00e9 en el estado de forma recientemente alcanzado para establecer una mejor marca mundial y pese al gran desaf\u00edo ya cumplido, desaprovechar esta ventaja ser\u00eda objeto seguro de un remordimiento futuro por mucho que hoy tuviera argumentos m\u00e1s que sobrados para no lleg\u00e1rmelo a plantear. La posibilidad de conseguir la ida y vuelta (<a href=\"https:\/\/drive.google.com\/file\/d\/0B5XVd3PlCrPZOS1ZY1lFb3o2MVU\/view\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Segovia-Bola del Mundo-Segovia<\/span><\/a>) se presentaba \u00fanica o en todo caso mucho m\u00e1s cercana que en pr\u00f3ximos a\u00f1os, sin duda m\u00e1s <em>normales<\/em> en mi preparaci\u00f3n f\u00edsica y mental.<\/p>\n<p>Tomada la decisi\u00f3n, nuevamente los entrenamientos intensivos y extensivos me obligaron a renunciar a muchos de los placeres vacacionales que tanto apetecen a la sociedad actual pero tan mal combinan con la exigencia del rendimiento deportivo, cuidando dieta y descanso pese a las tentaciones ofrecidas por una parte de mi entorno relacional que cada verano, inconscientemente, se obstina en dificultarme mis prop\u00f3sitos como una forma quiz\u00e1s de exorcizar su propia e inconfesada incapacidad de asumir una vida desde el compromiso que supone el esfuerzo constante por las metas a alcanzar.<\/p>\n<p>En un d\u00eda de agosto excepcionalmente frio, incluso para la zona m\u00e1s monta\u00f1osa del Sistema Central (a las 11:00 h. el Alto de Navacerrada registraba 5\u00b0 C. y en la cumbre de la Bola del Mundo, bajo cero, con niebla cerrada y ventisca horizontal) y pese a no disponer del equipamiento adecuado por lo inesperado de la situaci\u00f3n (corr\u00ed con pantal\u00f3n corto y una simple camiseta), finalic\u00e9 con \u00e9xito el reto y con \u00e9l nuevamente la convicci\u00f3n de que en la vida las oportunidades se nos presentan para aprovecharlas y no dejarlas pasar, aunque para ello haya que renunciar a la rutina y a la comodidad.<\/p>\n<p>Sinceramente, no cambio mis \u00faltimas vacaciones por las de ese merecido descanso que todos me invitaban a tomar\u2026<\/p>\n<p style=\"text-align: right;\"><em><strong>Saludos de Antonio J. Alonso Sampedro<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finaliza el XV Campeonato del Mundo de Atletismo 2015 celebrado en Pek\u00edn (los he seguido todos desde el primero de Helsinki en 1983) y presenciando embelesado cada prueba, una vez m\u00e1s me pregunto que lleva a los competidores a darlo todo hasta el final con independencia de las posibilidades de cada cual para ganar. Es &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Veranear: Una cuesti\u00f3n muy personal&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[68],"tags":[31],"class_list":["post-10919","post","type-post","status-publish","format-standard","hentry","category-marath-tiones-semanal","tag-vacaciones"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vacaciones, veranear\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"vacaciones,veranear,alonso-business coaching,antonio j. alonso,marath-tiones\/semanal\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"Vacaciones, veranear\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"504\" \/>\n\t\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t\t<meta property=\"article:tag\" content=\"vacaciones\" \/>\n\t\t<meta property=\"article:tag\" content=\"veranear\" \/>\n\t\t<meta property=\"article:tag\" content=\"alonso-business coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"antonio j. alonso\" \/>\n\t\t<meta property=\"article:tag\" content=\"marath-tiones\/semanal\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-04T23:00:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-24T18:22:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vacaciones, veranear\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#article\",\"name\":\"Veranear: Una cuesti\\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Veranear: Una cuesti\\u00f3n muy personal\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/Veranear.jpg?fit=504%2C369&ssl=1\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#articleImage\",\"width\":504,\"height\":369},\"datePublished\":\"2015-09-05T00:00:24+02:00\",\"dateModified\":\"2019-01-24T19:22:06+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#webpage\"},\"articleSection\":\"Marath-tiones\\\/semanal, vacaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/marath-tiones-semanal\\\/#listItem\",\"name\":\"Marath-tiones\\\/semanal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/marath-tiones-semanal\\\/#listItem\",\"position\":2,\"name\":\"Marath-tiones\\\/semanal\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/marath-tiones-semanal\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#listItem\",\"name\":\"Veranear: Una cuesti\\u00f3n muy personal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#listItem\",\"position\":3,\"name\":\"Veranear: Una cuesti\\u00f3n muy personal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/marath-tiones-semanal\\\/#listItem\",\"name\":\"Marath-tiones\\\/semanal\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/\",\"name\":\"Veranear: Una cuesti\\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro\",\"description\":\"Vacaciones, veranear\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/05-09-2015\\\/veranear-una-cuestion-muy-personal\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2015-09-05T00:00:24+02:00\",\"dateModified\":\"2019-01-24T19:22:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro","description":"Vacaciones, veranear","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/","robots":"max-image-preview:large","keywords":"vacaciones,veranear,alonso-business coaching,antonio j. alonso,marath-tiones\/semanal","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#article","name":"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro","headline":"Veranear: Una cuesti\u00f3n muy personal","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg?fit=504%2C369&ssl=1","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#articleImage","width":504,"height":369},"datePublished":"2015-09-05T00:00:24+02:00","dateModified":"2019-01-24T19:22:06+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#webpage"},"articleSection":"Marath-tiones\/semanal, vacaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/#listItem","name":"Marath-tiones\/semanal"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/#listItem","position":2,"name":"Marath-tiones\/semanal","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#listItem","name":"Veranear: Una cuesti\u00f3n muy personal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#listItem","position":3,"name":"Veranear: Una cuesti\u00f3n muy personal","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/#listItem","name":"Marath-tiones\/semanal"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/","name":"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro","description":"Vacaciones, veranear","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2015-09-05T00:00:24+02:00","dateModified":"2019-01-24T19:22:06+01:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro","og:description":"Vacaciones, veranear","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-09-2015\/veranear-una-cuestion-muy-personal\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg","og:image:width":504,"og:image:height":369,"article:tag":["vacaciones","veranear","alonso-business coaching","antonio j. alonso","marath-tiones\/semanal"],"article:published_time":"2015-09-04T23:00:24+00:00","article:modified_time":"2019-01-24T18:22:06+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary","twitter:site":"@AntonioJAlonso","twitter:title":"Veranear: Una cuesti\u00f3n muy personal | Blog de Antonio J. Alonso Sampedro","twitter:description":"Vacaciones, veranear","twitter:creator":"@AntonioJAlonso","twitter:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/08\/Veranear.jpg"},"aioseo_meta_data":{"post_id":"10919","title":"Veranear: Una cuesti\u00f3n muy personal | #site_title","description":"Vacaciones, veranear","keywords":[{"label":"Vacaciones","value":"Vacaciones"},{"label":"veranear","value":"veranear"},{"label":"Alonso-BUSINESS COACHING","value":"Alonso-BUSINESS COACHING"},{"label":"Antonio J. Alonso","value":"Antonio J. Alonso"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 17:12:47","updated":"2025-06-04 04:19:59","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-2Q7","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9494,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/04-02-2015\/marath-tiones-136\/","url_meta":{"origin":10919,"position":0},"title":"MARATH-TIONES&#8230; 136","author":"Antonio J. Alonso Sampedro","date":"04\/02\/2015","format":false,"excerpt":"Es mi intenci\u00f3n aplicar a Marathon-15% todo lo aprendido en mis trece a\u00f1os de ejercicio profesional como Business Coach, metodolog\u00eda propia que huye de la complicaci\u00f3n sicol\u00f3gico-emocional tan de moda hoy para centrarse en lo esencial, que es simplemente el actuar despu\u00e9s de valorar aplicando el sentido com\u00fan a cada\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":20990,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/04-03-2021\/ese-otro-lugar-donde-morar-hasta-el-final\/","url_meta":{"origin":10919,"position":1},"title":"Ese otro lugar donde morar hasta el final","author":"Antonio J. Alonso Sampedro","date":"04\/03\/2021","format":false,"excerpt":"Una semana atr\u00e1s, el jueves 25 de febrero de 2021, mi vida no quiso pero tuvo que cambiar. De ser hijo pas\u00e9 a un desorientado estado en el que ya no me pod\u00eda llamar como tal, perdiendo sin esperarlo todo lo que hab\u00eda constituido mi referencia ancestral. Hace treinta y\u2026","rel":"","context":"En \u00abPersonal\u00bb","block_context":{"text":"Personal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/personal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/03\/Simbolo-celta-madre-con-nino.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3152,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/13-11-2010\/mi-pregunta-mas-poderosa\/","url_meta":{"origin":10919,"position":2},"title":"Mi Pregunta m\u00e1s Poderosa","author":"Antonio J. Alonso Sampedro","date":"13\/11\/2010","format":false,"excerpt":"Soy de los que piensan que una pregunta siempre vale m\u00e1s que mil respuestas pues, estas, realmente solo lo son si antes se formula aquella. Adem\u00e1s, la pregunta abre los caminos que las respuestas tienden a cerrar. Preguntarse por todo lo que es y debe ser de nuestro inter\u00e9s es\u2026","rel":"","context":"En \u00abCoach-tiones\u00bb","block_context":{"text":"Coach-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/11\/Mi-pregunta-mas-poderosa.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12624,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/04-10-2016\/dedicacion-o-adiccion\/","url_meta":{"origin":10919,"position":3},"title":"\u00bfDEDICACI\u00d3N O ADICCI\u00d3N\u2026?","author":"Antonio J. Alonso Sampedro","date":"04\/10\/2016","format":false,"excerpt":"Uno de los signos que mejor definen nuestra contemporaneidad es la creciente dificultad para destacar en cualquier \u00e1mbito de la vida (personal, profesional, empresarial, pol\u00edtico, social, etc.), lo que determina una creciente competitividad que demanda cada vez m\u00e1s la dedicaci\u00f3n en todo aquello en lo se pretenda despuntar. Inmersos en\u2026","rel":"","context":"En \u00abMarath-tiones\/semanal\u00bb","block_context":{"text":"Marath-tiones\/semanal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/10\/Tras-finalizar-Marathon-15-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/10\/Tras-finalizar-Marathon-15-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/10\/Tras-finalizar-Marathon-15-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/10\/Tras-finalizar-Marathon-15-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/10\/Tras-finalizar-Marathon-15-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9880,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/23-03-2015\/marath-tiones-183\/","url_meta":{"origin":10919,"position":4},"title":"MARATH-TIONES&#8230; 183","author":"Antonio J. Alonso Sampedro","date":"23\/03\/2015","format":false,"excerpt":"Ayer, como parte del proyecto Marathon-15% y una vez m\u00e1s, me detuve un buen rato en una c\u00e9ntrica librer\u00eda a ojear los cientos de libros que, desde m\u00faltiples orientaciones, versan sobre superaci\u00f3n personal. Cada vez que hago esto no puedo negar mi desconsuelo al pensar que el m\u00edo pueda ser\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12436,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/06-09-2016\/la-psicologia-positiva-una-ciencia-de-la-felicidad\/","url_meta":{"origin":10919,"position":5},"title":"LA PSICOLOG\u00cdA POSITIVA\u2026 \u00bfUNA CIENCIA DE LA FELICIDAD?","author":"Antonio J. Alonso Sampedro","date":"06\/09\/2016","format":false,"excerpt":"Tras varios a\u00f1os publicando regular y convencidamente art\u00edculos sobre desarrollo y superaci\u00f3n personal, debo confesar que no tengo tantos lectores como me llegar\u00eda a gustar pero tambi\u00e9n que conozco la f\u00f3rmula para captarlos, aunque juro laicamente que nunca la voy a utilizar. \u00bfQu\u00e9 no me hace tan popular? A parte\u2026","rel":"","context":"En \u00abMarath-tiones\/semanal\u00bb","block_context":{"text":"Marath-tiones\/semanal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/"},"img":{"alt_text":"Flower-Power","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/09\/Flower-Power.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=10919"}],"version-history":[{"count":33,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10919\/revisions"}],"predecessor-version":[{"id":17175,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10919\/revisions\/17175"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=10919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=10919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=10919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}