{"id":10964,"date":"2015-09-08T00:00:28","date_gmt":"2015-09-07T23:00:28","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=10964"},"modified":"2015-09-02T18:02:39","modified_gmt":"2015-09-02T17:02:39","slug":"re-flexiones-1-077-adulto","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/","title":{"rendered":"Re-flexiones&#8230; 1.077 (adulto)"},"content":{"rendered":"<p style=\"text-align: center;\"><em>&#8220;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&#8221;<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Ogden_Nash\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" title=\"ogden-nash.jpg\" src=\"http:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470\" alt=\"ogden-nash.jpg\" width=\"86\" height=\"128\" border=\"0\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Ogden Nash<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&#8221; Ogden Nash<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[75],"tags":[86],"class_list":["post-10964","post","type-post","status-publish","format-standard","hentry","category-re-flexiones-tematicas","tag-adulto"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&quot; Ogden Nash\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"ogden nash,alonso-business coaching,antonio j. alonso,adulto,re-flexiones\/tem\u00e1ticas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ogden Nash | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&quot; Ogden Nash\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470\" \/>\n\t\t<meta property=\"article:tag\" content=\"ogden nash\" \/>\n\t\t<meta property=\"article:tag\" content=\"alonso-business coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"antonio j. alonso\" \/>\n\t\t<meta property=\"article:tag\" content=\"adulto\" \/>\n\t\t<meta property=\"article:tag\" content=\"re-flexiones\/tem\u00e1ticas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-07T23:00:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-02T17:02:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ogden Nash | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&quot; Ogden Nash\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#article\",\"name\":\"Ogden Nash | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Re-flexiones&#8230; 1.077 (adulto)\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/i0.wp.com\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/ogden-nash.thumbnail.jpg?w=470\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#articleImage\"},\"datePublished\":\"2015-09-08T00:00:28+02:00\",\"dateModified\":\"2015-09-02T18:02:39+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#webpage\"},\"articleSection\":\"Re-flexiones\\\/tem\\u00e1ticas, adulto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"position\":2,\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#listItem\",\"name\":\"Re-flexiones&#8230; 1.077 (adulto)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#listItem\",\"position\":3,\"name\":\"Re-flexiones&#8230; 1.077 (adulto)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/\",\"name\":\"Ogden Nash | Blog de Antonio J. Alonso Sampedro\",\"description\":\"\\\"La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra\\\" Ogden Nash\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-09-2015\\\/re-flexiones-1-077-adulto\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2015-09-08T00:00:28+02:00\",\"dateModified\":\"2015-09-02T18:02:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ogden Nash | Blog de Antonio J. Alonso Sampedro","description":"\"La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra\" Ogden Nash","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/","robots":"max-image-preview:large","keywords":"ogden nash,alonso-business coaching,antonio j. alonso,adulto,re-flexiones\/tem\u00e1ticas","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#article","name":"Ogden Nash | Blog de Antonio J. Alonso Sampedro","headline":"Re-flexiones&#8230; 1.077 (adulto)","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#articleImage"},"datePublished":"2015-09-08T00:00:28+02:00","dateModified":"2015-09-02T18:02:39+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#webpage"},"articleSection":"Re-flexiones\/tem\u00e1ticas, adulto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","name":"Re-flexiones\/tem\u00e1ticas"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","position":2,"name":"Re-flexiones\/tem\u00e1ticas","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#listItem","name":"Re-flexiones&#8230; 1.077 (adulto)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#listItem","position":3,"name":"Re-flexiones&#8230; 1.077 (adulto)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","name":"Re-flexiones\/tem\u00e1ticas"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/","name":"Ogden Nash | Blog de Antonio J. Alonso Sampedro","description":"\"La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra\" Ogden Nash","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2015-09-08T00:00:28+02:00","dateModified":"2015-09-02T18:02:39+02:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Ogden Nash | Blog de Antonio J. Alonso Sampedro","og:description":"&quot;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&quot; Ogden Nash","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-09-2015\/re-flexiones-1-077-adulto\/","fb:admins":"1290516206","og:image":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470","og:image:secure_url":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470","article:tag":["ogden nash","alonso-business coaching","antonio j. alonso","adulto","re-flexiones\/tem\u00e1ticas"],"article:published_time":"2015-09-07T23:00:28+00:00","article:modified_time":"2015-09-02T17:02:39+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary","twitter:site":"@AntonioJAlonso","twitter:title":"Ogden Nash | Blog de Antonio J. Alonso Sampedro","twitter:description":"&quot;La edad adulta es cuando te has encontrado con tanta gente que cada nueva persona te recuerda a otra&quot; Ogden Nash","twitter:creator":"@AntonioJAlonso","twitter:image":"http:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/02\/ogden-nash.thumbnail.jpg?w=470"},"aioseo_meta_data":{"post_id":"10964","title":"Ogden Nash | #site_title","description":null,"keywords":[{"label":"Ogden Nash","value":"Ogden Nash"},{"label":"Alonso-BUSINESS COACHING","value":"Alonso-BUSINESS COACHING"},{"label":"Antonio J. Alonso","value":"Antonio J. Alonso"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 17:12:48","updated":"2025-06-04 04:19:59","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-2QQ","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":10966,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/09-09-2015\/re-flexiones-1-078-adulto\/","url_meta":{"origin":10964,"position":0},"title":"Re-flexiones&#8230; 1.078 (adulto)","author":"Antonio J. Alonso Sampedro","date":"09\/09\/2015","format":false,"excerpt":"\"\u00bfQu\u00e9 es un adulto? Un ni\u00f1o inflado por la edad\" Simone de Beauvoir","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"simone-de-beauvoir.jpg","src":"http:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2012\/06\/simone-de-beauvoir.thumbnail.jpg?w=470&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10961,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/07-09-2015\/re-flexiones-1-076-adulto\/","url_meta":{"origin":10964,"position":1},"title":"Re-flexiones&#8230; 1.076 (adulto)","author":"Antonio J. Alonso Sampedro","date":"07\/09\/2015","format":false,"excerpt":"\"Ser adulto significa olvidar lo desconsolados que nos hemos sentido con frecuencia de ni\u00f1os\" Heinrich B\u00f6ll","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"Heinrich B\u00f6ll1","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/09\/Heinrich-B%C3%B6ll1-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":23821,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/07-01-2023\/re-flexiones-3-655-educacion\/","url_meta":{"origin":10964,"position":2},"title":"Re-flexiones&#8230; 3.655 (educaci\u00f3n)","author":"Antonio J. Alonso Sampedro","date":"07\/01\/2023","format":false,"excerpt":"\"Los ni\u00f1os son educados por lo que hace el adulto y no por lo que dice\" Carl Gustav Jung","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Carl-Gustav-Jung.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":30391,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/21-01-2026\/re-flexiones-4-819-vida\/","url_meta":{"origin":10964,"position":3},"title":"Re-flexiones&#8230; 4.819 (vida)","author":"Antonio J. Alonso Sampedro","date":"21\/01\/2026","format":false,"excerpt":"\"La vida pasa y el ser, como la bellota, como el ni\u00f1o, o a veces como el adulto, no advierte ese movimiento, ni lo impulsa ni lo estorba\" Le\u00f3n Tolst\u00f3i","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/12\/Le%C3%B3n-Tolst%C3%B3i1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/12\/Le%C3%B3n-Tolst%C3%B3i1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/12\/Le%C3%B3n-Tolst%C3%B3i1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23758,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-12-2022\/re-flexiones-3-648-educacion\/","url_meta":{"origin":10964,"position":4},"title":"Re-flexiones&#8230; 3.648 (educaci\u00f3n)","author":"Antonio J. Alonso Sampedro","date":"31\/12\/2022","format":false,"excerpt":"\"La educaci\u00f3n, para la mayor\u00eda, significa intentar que el ni\u00f1o se parezca al adulto t\u00edpico de su sociedad. Pero para m\u00ed, significa hacer creadores, tienes que hacer inventores, innovadores, y no conformistas\" Jean Piaget","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2019\/07\/Jean-Piaget.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2019\/07\/Jean-Piaget.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2019\/07\/Jean-Piaget.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2019\/07\/Jean-Piaget.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15524,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-06-2018\/re-flexiones-2-092-censura\/","url_meta":{"origin":10964,"position":5},"title":"Re-flexiones&#8230; 2.092 (censura)","author":"Antonio J. Alonso Sampedro","date":"19\/06\/2018","format":false,"excerpt":"\"Te quejas de las censuras de tus maestros, \u00e9mulos y adversarios, cuando debieras agradecerlas. Sus golpes no te hieren; te esculpen\" Santiago Ram\u00f3n y Cajal","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/06\/Ram%C3%B3n-y-Cajal-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=10964"}],"version-history":[{"count":1,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10964\/revisions"}],"predecessor-version":[{"id":10965,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/10964\/revisions\/10965"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=10964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=10964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=10964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}