{"id":11714,"date":"2016-03-28T00:00:52","date_gmt":"2016-03-27T23:00:52","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=11714"},"modified":"2022-04-20T18:44:28","modified_gmt":"2022-04-20T16:44:28","slug":"hacer-para-convencer","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/28-03-2016\/hacer-para-convencer\/","title":{"rendered":"\u00a1HACER&#8230; PARA CONVENCER!"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=3cNhok4JJQc\" target=\"_blank\" rel=\"attachment noopener wp-att-11716 noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"11716\" data-permalink=\"https:\/\/www.alonso-businesscoaching.es\/blog\/28-03-2016\/hacer-para-convencer\/crono-con-boton-de-inicio-pequeno\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/03\/Crono-con-boton-de-inicio-peque%C3%B1o.jpg?fit=571%2C359&amp;ssl=1\" data-orig-size=\"571,359\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Crono con boton de inicio peque\u00f1o\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/03\/Crono-con-boton-de-inicio-peque%C3%B1o.jpg?fit=525%2C330&amp;ssl=1\" class=\"aligncenter wp-image-11716\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/03\/Crono-con-boton-de-inicio-peque%C3%B1o.jpg?resize=442%2C278\" alt=\"Crono con boton de inicio peque\u00f1o\" width=\"442\" height=\"278\" srcset=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/03\/Crono-con-boton-de-inicio-peque%C3%B1o.jpg?w=571&amp;ssl=1 571w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/03\/Crono-con-boton-de-inicio-peque%C3%B1o.jpg?resize=300%2C189&amp;ssl=1 300w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><\/p>\n<p>Cuando hacia el final del verano del 2014 me entrevistaron en un programa de televisi\u00f3n para conocer sobre mi nuevo proyecto &#8220;Marathon-15%&#8221;, nadie entonces pod\u00eda saber cu\u00e1l ser\u00eda el desenlace de un prop\u00f3sito deportivo y editorial que ante todo pretend\u00eda validar aquello en lo que siempre he cre\u00eddo y pretend\u00eda demostrar: que las claves del desarrollo y la superaci\u00f3n personal son algo m\u00e1s que fr\u00eda y lejana teor\u00eda cuando en ellas honestamente nos comprometemos, apostando en nuestra actuaci\u00f3n con todo el esfuerzo y la voluntad. Tras su <a href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/2015\/06\/21\/lo-consegui\/\" target=\"_blank\" rel=\"noopener\">positiva finalizaci\u00f3n<\/a>, hoy puedo asegurar que nada puede convencer m\u00e1s que la ejemplificaci\u00f3n personal y con ella doy por recompensado este a\u00f1o y medio de intensa dedicaci\u00f3n a la consecuci\u00f3n de un <a href=\"https:\/\/drive.google.com\/file\/d\/1-XxkyGCTEQ4WKIxb25Uo_-LXwJuk3fA9\/view\" target=\"_blank\" rel=\"noopener\">r\u00e9cord mundial<\/a> y a la publicaci\u00f3n del <a href=\"https:\/\/www.amazon.es\/dp\/B01CNPIRFO\" target=\"_blank\" rel=\"noopener\">libro<\/a> que reflexivamente lo viene a testimoniar.<\/p>\n<p>Aspirar a ser Coach profesional puede quedar en solo una ilusionada pretensi\u00f3n sin posibilidades de consolidar. Todo depende del grado de compromiso con una labor que pide sobre todo coherencia entre lo dicho y lo hecho como \u00fanica manifestaci\u00f3n de honestidad ante quienes, deseosos de nuestra facilitaci\u00f3n, nos trasladan su confianza sin mayor justificaci\u00f3n que la de sus deseos por mejorar. Ser Coach (no por deseo sino por capacidad) obliga siempre a ejemplificar, siendo \u201cproducto de producto\u201d como innegociable requisito de ganada fiabilidad pues, en caso contrario, el dejar indolentemente que nuestros actos desmientan nuestras afirmaciones nos llevar\u00e1 pronto a fracasar.<\/p>\n<p>Desde 2002, tras tantos a\u00f1os de intensa profesi\u00f3n como Business Coach, conozco muchos casos de postulantes ilusionados que no han logrado continuar porque no entendieron que la facilidad del decir en nada se corresponde con la dificultad del actuar. Que los discursos de manual se desmoronan pronto cuando sus comportamientos les vienen a negar. Que no hay mayor autoridad que aquella que se vale de la demostraci\u00f3n propia como aval de verdad.<\/p>\n<p>\u00a1Hacer&#8230; para convencer!: no puede haber otra actuaci\u00f3n m\u00e1s eficaz\u2026<\/p>\n<p style=\"text-align: right;\"><em><strong>Saludos de Antonio J. Alonso<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando hacia el final del verano del 2014 me entrevistaron en un programa de televisi\u00f3n para conocer sobre mi nuevo proyecto &#8220;Marathon-15%&#8221;, nadie entonces pod\u00eda saber cu\u00e1l ser\u00eda el desenlace de un prop\u00f3sito deportivo y editorial que ante todo pretend\u00eda validar aquello en lo que siempre he cre\u00eddo y pretend\u00eda demostrar: que las claves del &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/28-03-2016\/hacer-para-convencer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;\u00a1HACER&#8230; PARA CONVENCER!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"yes","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[68],"tags":[150,70],"class_list":["post-11714","post","type-post","status-publish","format-standard","hentry","category-marath-tiones-semanal","tag-hacer","tag-marath-tiones"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-32W","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8314,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/26-09-2014\/marath-tiones-23\/","url_meta":{"origin":11714,"position":0},"title":"MARATH-TIONES&#8230; 23","author":"Antonio J. Alonso Sampedro","date":"26\/09\/2014","format":false,"excerpt":"Soy consciente de que, por m\u00e1s de que nos esforcemos en hacer las cosas bien, a las dificultades no hay que llamarlas para que nos visiten, sobre todo cuando somos los promotores de un proyecto. Mi tarea no es solo entrenar, sino que debo tambi\u00e9n escribir, coordinar a mi equipo\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12436,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/06-09-2016\/la-psicologia-positiva-una-ciencia-de-la-felicidad\/","url_meta":{"origin":11714,"position":1},"title":"LA PSICOLOG\u00cdA POSITIVA\u2026 \u00bfUNA CIENCIA DE LA FELICIDAD?","author":"Antonio J. Alonso Sampedro","date":"06\/09\/2016","format":false,"excerpt":"Tras varios a\u00f1os publicando regular y convencidamente art\u00edculos sobre desarrollo y superaci\u00f3n personal, debo confesar que no tengo tantos lectores como me llegar\u00eda a gustar pero tambi\u00e9n que conozco la f\u00f3rmula para captarlos, aunque juro laicamente que nunca la voy a utilizar. \u00bfQu\u00e9 no me hace tan popular? A parte\u2026","rel":"","context":"En \u00abMarath-tiones\/semanal\u00bb","block_context":{"text":"Marath-tiones\/semanal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/"},"img":{"alt_text":"Flower-Power","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/09\/Flower-Power.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9039,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/18-12-2014\/marath-tiones-94\/","url_meta":{"origin":11714,"position":2},"title":"MARATH-TIONES&#8230; 94","author":"Antonio J. Alonso Sampedro","date":"18\/12\/2014","format":false,"excerpt":"Recuper\u00e1ndome f\u00edsicamente de nuevo, cada vez estamos m\u00e1s cerca de llegar a descubrir el l\u00edmite adecuado de mi m\u00e1xima capacidad para entrenar Marathon-15%. No pasarse pero llegar es la clave para aprovechar todo el potencial de cada cual. La mejor versi\u00f3n de uno mismo depende de saber conjugar el deber\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12839,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/22-11-2016\/la-religion-y-la-humildad-de-todo-lo-demas\/","url_meta":{"origin":11714,"position":3},"title":"La religi\u00f3n y la humildad de todo lo dem\u00e1s","author":"Antonio J. Alonso Sampedro","date":"22\/11\/2016","format":false,"excerpt":"En mis art\u00edculos no suelo hablar de pol\u00edtica o de religi\u00f3n por una cuesti\u00f3n de econom\u00eda mental: lo que no tiene remedio no me debe preocupar. Es decir, nada se puede argumentar en torno a estos asuntos que pueda convencer a los dem\u00e1s. Son temas que se vienen a articular\u2026","rel":"","context":"En \u00abMarath-tiones\/semanal\u00bb","block_context":{"text":"Marath-tiones\/semanal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/11\/La-religion-y-la-humildad.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/11\/La-religion-y-la-humildad.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/11\/La-religion-y-la-humildad.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8793,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/12-11-2014\/marath-tiones-63\/","url_meta":{"origin":11714,"position":4},"title":"MARATH-TIONES&#8230; 63","author":"Antonio J. Alonso Sampedro","date":"12\/11\/2014","format":false,"excerpt":"Recientemente ha sido tema de Coloquio en nuestro grupo profesional FORO COACHING VALENCIA la Gesti\u00f3n del Tiempo como herramienta esencial de la eficiencia personal. Todo no se puede hacer y por tanto hay que priorizar, lo cual me lleva a pensar que para progresar en Marathon-15% algo m\u00e1s de lo\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9033,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/17-12-2014\/marath-tiones-93\/","url_meta":{"origin":11714,"position":5},"title":"MARATH-TIONES&#8230; 93","author":"Antonio J. Alonso Sampedro","date":"17\/12\/2014","format":false,"excerpt":"Mis antiguos compa\u00f1eros de trabajo (cuando yo prestaba mis servicios por cuenta ajena en entidades financieras) siempre me preguntan sobre mi grado de satisfacci\u00f3n desde que hace m\u00e1s de una d\u00e9cada ejerzo como Coach profesional de forma liberal. Siempre doy la misma respuesta: Pese a todo, que es mucho, nunca\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/11714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=11714"}],"version-history":[{"count":40,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/11714\/revisions"}],"predecessor-version":[{"id":22598,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/11714\/revisions\/22598"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=11714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=11714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=11714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}