{"id":12082,"date":"2016-06-27T00:00:28","date_gmt":"2016-06-26T23:00:28","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=12082"},"modified":"2016-06-10T16:43:54","modified_gmt":"2016-06-10T15:43:54","slug":"re-flexiones-1-370-amistad","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/","title":{"rendered":"Re-flexiones&#8230; 1.370 (amistad)"},"content":{"rendered":"<p style=\"text-align: center;\"><em>&#8220;S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos&#8221;<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Noel_Claras%C3%B3\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-11324\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras%C3%B31-150x150.jpg?resize=150%2C150\" alt=\"Noel Claras\u00f31\" width=\"150\" height=\"150\" \/><\/a>Noel Claras\u00f3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos&#8221; Noel Claras\u00f3<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[75],"tags":[108],"class_list":["post-12082","post","type-post","status-publish","format-standard","hentry","category-re-flexiones-tematicas","tag-amistad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"noel claras\u00f3,alonso-business coaching,antonio j. alonso,amistad,re-flexiones\/tem\u00e1ticas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg\" \/>\n\t\t<meta property=\"article:tag\" content=\"noel claras\u00f3\" \/>\n\t\t<meta property=\"article:tag\" content=\"alonso-business coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"antonio j. alonso\" \/>\n\t\t<meta property=\"article:tag\" content=\"amistad\" \/>\n\t\t<meta property=\"article:tag\" content=\"re-flexiones\/tem\u00e1ticas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-26T23:00:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-10T15:43:54+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#article\",\"name\":\"Noel Claras\\u00f3 | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Re-flexiones&#8230; 1.370 (amistad)\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Noel-Claras\\u00f31-150x150.jpg\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#articleImage\"},\"datePublished\":\"2016-06-27T00:00:28+02:00\",\"dateModified\":\"2016-06-10T16:43:54+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#webpage\"},\"articleSection\":\"Re-flexiones\\\/tem\\u00e1ticas, amistad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"position\":2,\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#listItem\",\"name\":\"Re-flexiones&#8230; 1.370 (amistad)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#listItem\",\"position\":3,\"name\":\"Re-flexiones&#8230; 1.370 (amistad)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-tematicas\\\/#listItem\",\"name\":\"Re-flexiones\\\/tem\\u00e1ticas\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/\",\"name\":\"Noel Claras\\u00f3 | Blog de Antonio J. Alonso Sampedro\",\"description\":\"S\\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/27-06-2016\\\/re-flexiones-1-370-amistad\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2016-06-27T00:00:28+02:00\",\"dateModified\":\"2016-06-10T16:43:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro","description":"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/","robots":"max-image-preview:large","keywords":"noel claras\u00f3,alonso-business coaching,antonio j. alonso,amistad,re-flexiones\/tem\u00e1ticas","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#article","name":"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro","headline":"Re-flexiones&#8230; 1.370 (amistad)","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#articleImage"},"datePublished":"2016-06-27T00:00:28+02:00","dateModified":"2016-06-10T16:43:54+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#webpage"},"articleSection":"Re-flexiones\/tem\u00e1ticas, amistad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","name":"Re-flexiones\/tem\u00e1ticas"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","position":2,"name":"Re-flexiones\/tem\u00e1ticas","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#listItem","name":"Re-flexiones&#8230; 1.370 (amistad)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#listItem","position":3,"name":"Re-flexiones&#8230; 1.370 (amistad)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/#listItem","name":"Re-flexiones\/tem\u00e1ticas"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/","name":"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro","description":"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2016-06-27T00:00:28+02:00","dateModified":"2016-06-10T16:43:54+02:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro","og:description":"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-06-2016\/re-flexiones-1-370-amistad\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg","article:tag":["noel claras\u00f3","alonso-business coaching","antonio j. alonso","amistad","re-flexiones\/tem\u00e1ticas"],"article:published_time":"2016-06-26T23:00:28+00:00","article:modified_time":"2016-06-10T15:43:54+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary","twitter:site":"@AntonioJAlonso","twitter:title":"Noel Claras\u00f3 | Blog de Antonio J. Alonso Sampedro","twitter:description":"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos","twitter:creator":"@AntonioJAlonso","twitter:image":"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/11\/Noel-Claras\u00f31-150x150.jpg"},"aioseo_meta_data":{"post_id":"12082","title":"Noel Claras\u00f3 | #site_title","description":"S\u00f3lo un buen amigo es capaz de comprender que su presencia puede llegar a molestarnos","keywords":[{"label":"Noel Claras\u00f3","value":"Noel Claras\u00f3"},{"label":"Alonso-BUSINESS COACHING","value":"Alonso-BUSINESS COACHING"},{"label":"Antonio J. Alonso","value":"Antonio J. Alonso"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 17:21:25","updated":"2025-06-04 04:56:22","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-38S","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11940,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/26-05-2016\/re-flexiones-1-338-amistad\/","url_meta":{"origin":12082,"position":0},"title":"Re-flexiones&#8230; 1.338 (amistad)","author":"Antonio J. Alonso Sampedro","date":"26\/05\/2016","format":false,"excerpt":"\"La amistad lo es todo. La amistad vale m\u00e1s que el talento. Vale m\u00e1s que el gobierno. La amistad vale casi tanto como la familia\" Mario Puzo","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"Mario Puzo1","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/05\/Mario-Puzo1-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11868,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/18-05-2016\/re-flexiones-1-330-amistad\/","url_meta":{"origin":12082,"position":1},"title":"Re-flexiones&#8230; 1.330 (amistad)","author":"Antonio J. Alonso Sampedro","date":"18\/05\/2016","format":false,"excerpt":"\"Amistad que acaba no hab\u00eda comenzado\" Publio Siro","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"Publio Siro1","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2016\/04\/Publio-Siro1-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12018,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/12-06-2016\/re-flexiones-1-355-amistad\/","url_meta":{"origin":12082,"position":2},"title":"Re-flexiones&#8230; 1.355 (amistad)","author":"Antonio J. Alonso Sampedro","date":"12\/06\/2016","format":false,"excerpt":"\"La amistad siempre es provechosa; el amor a veces hiere\" S\u00e9neca","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2022\/03\/Seneca1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12097,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/03-07-2016\/re-flexiones-1-376-amistad\/","url_meta":{"origin":12082,"position":3},"title":"Re-flexiones&#8230; 1.376 (amistad)","author":"Antonio J. Alonso Sampedro","date":"03\/07\/2016","format":false,"excerpt":"\"La amistad es animal de compa\u00f1\u00eda, no de reba\u00f1o\" Plutarco","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"plutarco.jpg","src":"http:\/\/i2.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2012\/06\/plutarco.thumbnail.jpg?w=470&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12115,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/07-07-2016\/re-flexiones-1-380-amistad\/","url_meta":{"origin":12082,"position":4},"title":"Re-flexiones&#8230; 1.380 (amistad)","author":"Antonio J. Alonso Sampedro","date":"07\/07\/2016","format":false,"excerpt":"\"La amistad es un comercio desinteresado entre semejantes\" Oliver Goldsmith","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"Oliver Goldsmith","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/06\/Oliver-Goldsmith-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12196,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/25-07-2016\/re-flexiones-1-398-amistad\/","url_meta":{"origin":12082,"position":5},"title":"Re-flexiones&#8230; 1.398 (amistad)","author":"Antonio J. Alonso Sampedro","date":"25\/07\/2016","format":false,"excerpt":"\"No tengas amistad con quien tenga poderosos enemigos\" Ram\u00f3n Llull","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"Ram\u00f3n Llull","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/11\/Ram%C3%B3n-Llull-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/12082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=12082"}],"version-history":[{"count":1,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/12082\/revisions"}],"predecessor-version":[{"id":12083,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/12082\/revisions\/12083"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=12082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=12082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=12082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}