{"id":2912,"date":"2011-12-19T12:41:17","date_gmt":"2011-12-19T12:41:17","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/2011\/12\/19\/re-flexiones-171\/"},"modified":"2011-12-19T12:41:17","modified_gmt":"2011-12-19T12:41:17","slug":"re-flexiones-171","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/","title":{"rendered":"Re-flexiones&#8230; 171"},"content":{"rendered":"<p align=\"center\"><em>\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d<\/em><\/p>\n<p align=\"center\"><a target=\"_blank\" href=\"http:\/\/en.wikipedia.org\/wiki\/Charles_Caleb_Colton\" title=\"charles-caleb-colton.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg?w=525\" alt=\"charles-caleb-colton.jpg\" border=\"0\" title=\"charles-caleb-colton.jpg\" \/><\/a>\u00a0<\/p>\n<p align=\"center\">Charles Caleb Colton<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d \u00a0 Charles Caleb Colton<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23],"tags":[],"class_list":["post-2912","post","type-post","status-publish","format-standard","hentry","category-re-flexiones-generales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"re-flexiones\/generales\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg\" \/>\n\t\t<meta property=\"article:tag\" content=\"re-flexiones\/generales\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-12-19T12:41:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-12-19T12:41:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#article\",\"name\":\"Re-flexiones\\u2026 171 | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Re-flexiones&#8230; 171\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/12\\\/charles-caleb-colton.thumbnail.jpg\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#articleImage\"},\"datePublished\":\"2011-12-19T12:41:17+01:00\",\"dateModified\":\"2011-12-19T12:41:17+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#webpage\"},\"articleSection\":\"Re-flexiones\\\/generales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"name\":\"Re-flexiones\\\/generales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"position\":2,\"name\":\"Re-flexiones\\\/generales\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#listItem\",\"name\":\"Re-flexiones&#8230; 171\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#listItem\",\"position\":3,\"name\":\"Re-flexiones&#8230; 171\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"name\":\"Re-flexiones\\\/generales\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/\",\"name\":\"Re-flexiones\\u2026 171 | Blog de Antonio J. Alonso Sampedro\",\"description\":\"\\u201cEl mayor amigo de la verdad es el Tiempo y su m\\u00e1s encarnizado enemigo, el Prejuicio\\u201d Charles Caleb Colton\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/19-12-2011\\\/re-flexiones-171\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2011-12-19T12:41:17+01:00\",\"dateModified\":\"2011-12-19T12:41:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro","description":"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/","robots":"max-image-preview:large","keywords":"re-flexiones\/generales","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#article","name":"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro","headline":"Re-flexiones&#8230; 171","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#articleImage"},"datePublished":"2011-12-19T12:41:17+01:00","dateModified":"2011-12-19T12:41:17+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#webpage"},"articleSection":"Re-flexiones\/generales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","name":"Re-flexiones\/generales"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","position":2,"name":"Re-flexiones\/generales","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#listItem","name":"Re-flexiones&#8230; 171"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#listItem","position":3,"name":"Re-flexiones&#8230; 171","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","name":"Re-flexiones\/generales"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/","name":"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro","description":"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2011-12-19T12:41:17+01:00","dateModified":"2011-12-19T12:41:17+01:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro","og:description":"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2011\/re-flexiones-171\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg","article:tag":["re-flexiones\/generales"],"article:published_time":"2011-12-19T12:41:17+00:00","article:modified_time":"2011-12-19T12:41:17+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary_large_image","twitter:site":"@AntonioJAlonso","twitter:title":"Re-flexiones\u2026 171 | Blog de Antonio J. Alonso Sampedro","twitter:description":"\u201cEl mayor amigo de la verdad es el Tiempo y su m\u00e1s encarnizado enemigo, el Prejuicio\u201d Charles Caleb Colton","twitter:creator":"@AntonioJAlonso","twitter:image":"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/12\/charles-caleb-colton.thumbnail.jpg"},"aioseo_meta_data":{"post_id":"2912","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 16:37:07","updated":"2025-06-04 01:44:17","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-KY","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":20542,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/13-12-2020\/3-000-re-flexiones\/","url_meta":{"origin":2912,"position":0},"title":"El tercer millar de Re-flexiones para meditar\u2026","author":"Antonio J. Alonso Sampedro","date":"13\/12\/2020","format":false,"excerpt":"El 19 de Marzo de 2018 escrib\u00ed\u2026 \"El segundo millar de Re-flexiones para meditar\u2026\". Hoy publico aqu\u00ed, en \u201cEl Blog Personal de Alonso-BUSINESS COACHING\u201d, la \u201cRe-flexi\u00f3n\u201d n\u00famero 3.000. Tres millares ordenadas en dos Categor\u00edas (\u201cRe-flexiones\/generales\u201d y \u201cRe-flexiones\/tem\u00e1ticas\u201d), todas sin repetici\u00f3n y bajo los mismos signos de identidad: cita de personaje\u2026","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2020\/11\/Leer-y-pensar.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":25626,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/19-12-2023\/4-000-re-flexiones-para-meditar\/","url_meta":{"origin":2912,"position":1},"title":"4.000 &#8220;Re-flexiones&#8221; para meditar\u2026","author":"Antonio J. Alonso Sampedro","date":"19\/12\/2023","format":false,"excerpt":"El 13 de diciembre de 2020 escrib\u00ed\u2026 \u201cEl tercer millar de Re-flexiones para meditar\u2026\u201d. Hoy publico aqu\u00ed, en \u201cEl Blog Personal de Alonso-BUSINESS COACHING\u201d, la \u201cRe-flexi\u00f3n\u201d n\u00famero 4.000; cuatro millares ordenadas en dos Categor\u00edas (\u201cRe-flexiones\/generales\u201d y \u201cRe-flexiones\/tem\u00e1ticas\u201d), todas sin repetici\u00f3n y bajo los mismos signos de identidad: cita de personaje\u2026","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/08\/El-pensador.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":31747,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/22-07-2026\/5-000-re-flexiones-para-meditar\/","url_meta":{"origin":2912,"position":2},"title":"5.000 &#8220;Re-flexiones&#8221; para meditar&#8230;","author":"Antonio J. Alonso Sampedro","date":"22\/07\/2026","format":false,"excerpt":"El 19 de diciembre de 2023 escrib\u00ed aqu\u00ed \"4.000 Re-flexiones para meditar...\". Hoy publico en \u201cEl Blog de Antonio J. Alonso Sampedro\u201d la \u201cRe-flexi\u00f3n\u201d n\u00famero 5.000; cinco millares ordenadas en dos Categor\u00edas (\u201cRe-flexiones\/generales\u201d y \u201cRe-flexiones\/tem\u00e1ticas\u201d), todas sin repetici\u00f3n y bajo los mismos signos de identidad: cita de personaje hist\u00f3rico, su\u2026","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/08\/El-pensador.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2644,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/22-08-2012\/re-flexiones-393\/","url_meta":{"origin":2912,"position":3},"title":"Re-flexiones&#8230; 393","author":"Antonio J. Alonso Sampedro","date":"22\/08\/2012","format":false,"excerpt":"\u201cEl trabajo transforma el talento en genio\u201d \u00a0 Anna Pavlova","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3305,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/13-12-2012\/re-flexiones-480\/","url_meta":{"origin":2912,"position":4},"title":"Re-flexiones&#8230; 480","author":"Antonio J. Alonso Sampedro","date":"13\/12\/2012","format":false,"excerpt":"\u201cMira si ser\u00e1 malo el trabajo, que deben pagarte para que lo hagas\u201d Facundo Cabral","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2012\/12\/Facundo-Cabral1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3904,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/12-04-2013\/re-flexiones-570\/","url_meta":{"origin":2912,"position":5},"title":"Re-flexiones&#8230; 570","author":"Antonio J. Alonso Sampedro","date":"12\/04\/2013","format":false,"excerpt":"\"El trabajo m\u00e1s productivo es el que sale de las manos de un hombre contento\" Victor Pauchet","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"Victor Pauchet","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/03\/Victor-Pauchet-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/2912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=2912"}],"version-history":[{"count":0,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/2912\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=2912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=2912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=2912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}