{"id":3176,"date":"2010-05-08T18:44:23","date_gmt":"2010-05-08T17:44:23","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/2010\/05\/08\/lecciones-de-ternura\/"},"modified":"2019-03-13T19:43:40","modified_gmt":"2019-03-13T18:43:40","slug":"lecciones-de-ternura","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/","title":{"rendered":"Lecciones de Ternura"},"content":{"rendered":"<p align=\"left\"><a href=\"https:\/\/www.alonso-businesscoaching.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"16382\" data-permalink=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/lecciones-de-ternura-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?fit=572%2C382&amp;ssl=1\" data-orig-size=\"572,382\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lecciones de ternura\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?fit=525%2C351&amp;ssl=1\" class=\"aligncenter size-full wp-image-16382\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?resize=525%2C351&#038;ssl=1\" alt=\"\" width=\"525\" height=\"351\" srcset=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?w=572&amp;ssl=1 572w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"left\">El lunes pasado, en pleno mayo, amaneci\u00f3 un d\u00eda fresco y lluvioso en Valencia. De esos que parecen se han equivocado de estaci\u00f3n para recordarnos un invierno reci\u00e9n finalizado que todos queremos olvidar pero que, sin pedirlo, en menos de un a\u00f1o nos volver\u00e1 a visitar.<\/p>\n<p>Es en este tipo de d\u00edas cuando me resulta m\u00e1s f\u00e1cil el poder analizar emocionalmente lo que me pasa y rodea, ganando en sentido y sensibilidad (\u00a1Jane Austen solo pod\u00eda ser brit\u00e1nica!).<\/p>\n<p>Caminando bajo la lluvia, recordaba la sesi\u00f3n de Coaching reci\u00e9n finalizada en donde el Gerente de una compa\u00f1\u00eda de servicios me hab\u00eda trasladado su preocupaci\u00f3n por el progresivo deterioro que estaba notando en la relaci\u00f3n laboral con su esposa (trabajan juntos) debido, seg\u00fan \u00e9l, a la crispaci\u00f3n que estos tiempos problem\u00e1ticos de dificultad econ\u00f3mica genera en quienes tienen responsabilidad en las empresas de liderar.<\/p>\n<p>Instalado en el metro y ya de vuelta a casa, segu\u00eda absorto en mis tribulaciones sobre las verdaderas razones que podr\u00edan explicar la situaci\u00f3n de mi cliente cuando en la parada de una estaci\u00f3n entraron dos j\u00f3venes con rasgos f\u00edsicos de s\u00edndrome de Down. Tendr\u00edan veintipocos a\u00f1os y no les acompa\u00f1aba nadie, lo que evidenciaba su autonom\u00eda personal. Vest\u00edan a la moda y permanec\u00edan callados, ajenos a un mundo que no les considera igual.<\/p>\n<p>A hora punta, el vag\u00f3n lleno no ofrec\u00eda muchas posibilidades de asiento y la \u00fanica plaza a la vista fue cedida galantemente por el muchacho a su acompa\u00f1ante, muy rubia y algo m\u00e1s alta que \u00e9l. Como no llevaban paraguas, sus ropas y pelos mojados me informaron de un largo trayecto a pi\u00e9 hasta esa estaci\u00f3n.<\/p>\n<p>Sin pretender mirar m\u00e1s all\u00e1 de lo que el decoro impone, me costaba apartar mis ojos de esos j\u00f3venes, distintos s\u00ed, pero a la vez tan normales en su comportamiento que todav\u00eda me intrigaban m\u00e1s. Y de repente, pas\u00f3\u2026<\/p>\n<p>Tuve el privilegio de contemplar una de las escenas m\u00e1s verdaderas y tiernas que en mucho tiempo he podido presenciar y que transcurri\u00f3 desapercibida para el resto del pasaje, tan ausentes como ignorantes de aquel regalo emocional.<\/p>\n<p>El muchacho, con un delicad\u00edsimo cuidado y esa minuciosidad titubeante que solo los s\u00edndrome de Down son capaces de mostrar (lo conozco muy bien, pues tengo una adorable primita que naci\u00f3 as\u00ed), le estaba retirando primorosamente del rostro los despeinados mechones mojados que cubr\u00edan sus ojos, dibujando nuevamente ese flequillo perdido, pelo a pelo, ante la dulce y plenamente azul mirada de la joven. \u00a1No pude contener mi emoci\u00f3n!<\/p>\n<p>Al pronto comprend\u00ed que las lecciones no las dan los que quieren sino los que pueden y que mi cliente, de haber estado all\u00ed, hubiera descubierto sin m\u00e1s ayuda m\u00eda la verdadera raz\u00f3n de su preocupaci\u00f3n&#8230;.<\/p>\n<p style=\"text-align: right;\" align=\"center\"><strong><em>Saludos de Antonio J. Alonso Sampedro<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes pasado, en pleno mayo, amaneci\u00f3 un d\u00eda fresco y lluvioso en Valencia. De esos que parecen se han equivocado de estaci\u00f3n para recordarnos un invierno reci\u00e9n finalizado que todos queremos olvidar pero que, sin pedirlo, en menos de un a\u00f1o nos volver\u00e1 a visitar. Es en este tipo de d\u00edas cuando me resulta &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Lecciones de Ternura&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[25],"tags":[51],"class_list":["post-3176","post","type-post","status-publish","format-standard","hentry","category-coach-tiones","tag-emocion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Emoci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"emoci\u00f3n,el blog personal de alonso-business coaching,antonio j alonso sampedro,desarrollo personal,coaching,coach-tiones\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"Emoci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"572\" \/>\n\t\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t\t<meta property=\"article:tag\" content=\"emoci\u00f3n\" \/>\n\t\t<meta property=\"article:tag\" content=\"el blog personal de alonso-business coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"antonio j alonso sampedro\" \/>\n\t\t<meta property=\"article:tag\" content=\"desarrollo personal\" \/>\n\t\t<meta property=\"article:tag\" content=\"coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"coach-tiones\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-05-08T17:44:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-03-13T18:43:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Emoci\u00f3n\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#article\",\"name\":\"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Lecciones de Ternura\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/Lecciones-de-ternura.jpg?fit=572%2C382&ssl=1\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#articleImage\",\"width\":572,\"height\":382},\"datePublished\":\"2010-05-08T18:44:23+02:00\",\"dateModified\":\"2019-03-13T19:43:40+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#webpage\"},\"articleSection\":\"Coach-tiones, emoci\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"name\":\"Coach-tiones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"position\":2,\"name\":\"Coach-tiones\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#listItem\",\"name\":\"Lecciones de Ternura\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#listItem\",\"position\":3,\"name\":\"Lecciones de Ternura\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"name\":\"Coach-tiones\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/\",\"name\":\"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro\",\"description\":\"Emoci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/08-05-2010\\\/lecciones-de-ternura\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2010-05-08T18:44:23+02:00\",\"dateModified\":\"2019-03-13T19:43:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro","description":"Emoci\u00f3n","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/","robots":"max-image-preview:large","keywords":"emoci\u00f3n,el blog personal de alonso-business coaching,antonio j alonso sampedro,desarrollo personal,coaching,coach-tiones","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#article","name":"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro","headline":"Lecciones de Ternura","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg?fit=572%2C382&ssl=1","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#articleImage","width":572,"height":382},"datePublished":"2010-05-08T18:44:23+02:00","dateModified":"2019-03-13T19:43:40+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#webpage"},"articleSection":"Coach-tiones, emoci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","name":"Coach-tiones"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","position":2,"name":"Coach-tiones","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#listItem","name":"Lecciones de Ternura"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#listItem","position":3,"name":"Lecciones de Ternura","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","name":"Coach-tiones"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/","name":"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro","description":"Emoci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2010-05-08T18:44:23+02:00","dateModified":"2019-03-13T19:43:40+01:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro","og:description":"Emoci\u00f3n","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-05-2010\/lecciones-de-ternura\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg","og:image:width":572,"og:image:height":382,"article:tag":["emoci\u00f3n","el blog personal de alonso-business coaching","antonio j alonso sampedro","desarrollo personal","coaching","coach-tiones"],"article:published_time":"2010-05-08T17:44:23+00:00","article:modified_time":"2019-03-13T18:43:40+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary","twitter:site":"@AntonioJAlonso","twitter:title":"Lecciones de Ternura | Blog de Antonio J. Alonso Sampedro","twitter:description":"Emoci\u00f3n","twitter:creator":"@AntonioJAlonso","twitter:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/05\/Lecciones-de-ternura.jpg"},"aioseo_meta_data":{"post_id":"3176","title":"Lecciones de Ternura | #site_title","description":"Emoci\u00f3n","keywords":[{"label":"Emoci\u00f3n","value":"Emoci\u00f3n"},{"label":"El Blog Personal de Alonso-BUSINESS COACHING","value":"El Blog Personal de Alonso-BUSINESS COACHING"},{"label":"Antonio J Alonso Sampedro","value":"Antonio J Alonso Sampedro"},{"label":"desarrollo personal","value":"desarrollo personal"},{"label":"Coaching","value":"Coaching"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 16:31:31","updated":"2025-06-04 01:15:44","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-Pe","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8918,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/02-12-2014\/marath-tiones-80\/","url_meta":{"origin":3176,"position":0},"title":"MARATH-TIONES&#8230; 80","author":"Antonio J. Alonso Sampedro","date":"02\/12\/2014","format":false,"excerpt":"Debo confesar que el acudir peri\u00f3dicamente en ayunas a realizarme los an\u00e1lisis cl\u00ednico-deportivos que controlan mi estado de salud durante los exigentes entrenamientos para Marathon-15% me pone de bastante mal humor intestinal, hasta que salgo y cruzando la calle abordo un conocido bar y en \u00e9l su deliciosa tortilla de\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":31355,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-04-2026\/en-la-semana-santa-marinera-ayer-vi-a-charlton-heston-desfilar\/","url_meta":{"origin":3176,"position":1},"title":"En la Semana Santa Marinera&#8230; \u00a1vi a Charlton Heston desfilar!","author":"Antonio J. Alonso Sampedro","date":"05\/04\/2026","format":false,"excerpt":"El pasado Jueves Santo, terminado el Telediario de las tres y sin soluci\u00f3n de continuidad, Televisi\u00f3n Espa\u00f1ola de nuevo nos ofreci\u00f3 \u201cLos diez mandamientos\u201d (Cecil B. DeMile-1956) con un Mois\u00e9s\/Charlton Heston descomunal. El Viernes Santo se repiti\u00f3 el ritual, esta vez (de nuevo) con \u201cBen-Hur\u201d (William Wyler-1959) y el mismo\u2026","rel":"","context":"En \u00abCine-tiones\u00bb","block_context":{"text":"Cine-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/cine-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2026\/04\/Romanos-en-la-Procesion-del-Santo-Entierro.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19155,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/24-03-2020\/corona-tiones-10\/","url_meta":{"origin":3176,"position":2},"title":"Corona-tiones&#8230; 10","author":"Antonio J. Alonso Sampedro","date":"24\/03\/2020","format":false,"excerpt":"LA \u201cPSICOSIS\u201d QUE NO DEBER\u00cdA SER TAL Una manera muy eficaz de enfrentarse a los problemas es la de relativizar, comparando con otros casos ese que nos angustia por su aparente gravedad. Reci\u00e9n anunciada la moratoria del confinamiento domiciliario por dos semanas m\u00e1s, de momento y en total ser\u00e1n cuatro\u2026","rel":"","context":"En \u00abCorona-tiones\u00bb","block_context":{"text":"Corona-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/corona-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2020\/03\/Psic%C3%B3sis.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2020\/03\/Psic%C3%B3sis.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2020\/03\/Psic%C3%B3sis.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":6459,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/14-12-2013\/la-mueblerizacion-de-la-vida\/","url_meta":{"origin":3176,"position":3},"title":"La &#8220;mueblerizaci\u00f3n&#8221; de la Vida","author":"Antonio J. Alonso Sampedro","date":"14\/12\/2013","format":false,"excerpt":"Confieso que, tras diecis\u00e9is a\u00f1os de satisfactoria residencia en mi vivienda, cada d\u00eda al entrar en ella me tranquilizo al comprobar que el mobiliario de su interior parece ser adecuado y actual, no percibiendo en absoluto la necesidad o tan siquiera conveniencia de ning\u00fan cambio a realizar. \u00a1Qu\u00e9 equivocado estoy,\u2026","rel":"","context":"En \u00abCoach-tiones\u00bb","block_context":{"text":"Coach-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/"},"img":{"alt_text":"Viejo sofa","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/12\/Viejo-sofa.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3147,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/18-12-2010\/marta-dominguez-y-el-estado-de-alarma\/","url_meta":{"origin":3176,"position":4},"title":"Marta Dom\u00ednguez y el Estado de Alarma","author":"Antonio J. Alonso Sampedro","date":"18\/12\/2010","format":false,"excerpt":"El profundo cambio de valores socio-culturales que el reci\u00e9n finalizado siglo XX ha provocado en la humanidad viene caracterizado por la instauraci\u00f3n de algunos estilos de actuaci\u00f3n personal que ya se han convertido en \u201cobligatorias doctrinas de comportamiento\u201d. Una de las m\u00e1s evidentes en las sociedades desarrolladas es la aceptaci\u00f3n\u2026","rel":"","context":"En \u00abCoach-tiones\u00bb","block_context":{"text":"Coach-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/"},"img":{"alt_text":"Marta Dominguez","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2010\/12\/Marta-Dominguez1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22028,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/11-12-2021\/la-butterfly-de-una-rebeka-sensacional\/","url_meta":{"origin":3176,"position":5},"title":"La Butterfly de una Rebeka sensacional","author":"Antonio J. Alonso Sampedro","date":"11\/12\/2021","format":false,"excerpt":"En el repertorio oper\u00edstico tradicional, junto con \u201cCarmen\u201d y \u201cLa Traviata\u201d, \u201cMadama Butterfly\u201d (G. Puccini-1904) es una de esas obras cuya protagonista no puede fallar, condicionando el \u00e9xito o fracaso de la representaci\u00f3n al margen de todo lo dem\u00e1s. Ayer, Marina Rebeka, elev\u00f3 a la categor\u00eda de acontecimiento vocal la\u2026","rel":"","context":"En \u00abMusic-tiones\u00bb","block_context":{"text":"Music-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/music-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/12\/20211210_192535-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/3176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=3176"}],"version-history":[{"count":9,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/3176\/revisions"}],"predecessor-version":[{"id":17638,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/3176\/revisions\/17638"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=3176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=3176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=3176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}