{"id":5594,"date":"2013-08-31T00:00:51","date_gmt":"2013-08-30T23:00:51","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=5594"},"modified":"2013-07-24T19:21:56","modified_gmt":"2013-07-24T18:21:56","slug":"re-flexiones-695","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/","title":{"rendered":"Re-flexiones&#8230; 695"},"content":{"rendered":"<p style=\"text-align: center;\"><em>&#8220;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&#8221;<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/es.wikipedia.org\/wiki\/Colin_Powell\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5596\" data-permalink=\"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/colin-powell\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg?fit=355%2C522&amp;ssl=1\" data-orig-size=\"355,522\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Colin Powell\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg?fit=355%2C522&amp;ssl=1\" class=\"aligncenter size-thumbnail wp-image-5596\" alt=\"Colin Powell\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell-150x150.jpg?resize=150%2C150\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg?resize=59%2C59&amp;ssl=1 59w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Colin Powell<\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>&#8220;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&#8221; Colin Powell<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23],"tags":[],"class_list":["post-5594","post","type-post","status-publish","format-standard","hentry","category-re-flexiones-generales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&quot; Colin Powell\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"re-flexiones\/generales\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&quot; Colin Powell\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"355\" \/>\n\t\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t\t<meta property=\"article:tag\" content=\"re-flexiones\/generales\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-08-30T23:00:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-07-24T18:21:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&quot; Colin Powell\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#article\",\"name\":\"Re-flexiones\\u2026 695 | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"Re-flexiones&#8230; 695\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/Colin-Powell-150x150.jpg\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#articleImage\"},\"datePublished\":\"2013-08-31T00:00:51+02:00\",\"dateModified\":\"2013-07-24T19:21:56+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#webpage\"},\"articleSection\":\"Re-flexiones\\\/generales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"name\":\"Re-flexiones\\\/generales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"position\":2,\"name\":\"Re-flexiones\\\/generales\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#listItem\",\"name\":\"Re-flexiones&#8230; 695\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#listItem\",\"position\":3,\"name\":\"Re-flexiones&#8230; 695\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/re-flexiones-generales\\\/#listItem\",\"name\":\"Re-flexiones\\\/generales\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/\",\"name\":\"Re-flexiones\\u2026 695 | Blog de Antonio J. Alonso Sampedro\",\"description\":\"\\\"No hay secretos para el \\u00e9xito: preparaci\\u00f3n, trabajo arduo y aprendizaje del fracaso\\\" Colin Powell\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/31-08-2013\\\/re-flexiones-695\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2013-08-31T00:00:51+02:00\",\"dateModified\":\"2013-07-24T19:21:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro","description":"\"No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso\" Colin Powell","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/","robots":"max-image-preview:large","keywords":"re-flexiones\/generales","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#article","name":"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro","headline":"Re-flexiones&#8230; 695","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell-150x150.jpg","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#articleImage"},"datePublished":"2013-08-31T00:00:51+02:00","dateModified":"2013-07-24T19:21:56+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#webpage"},"articleSection":"Re-flexiones\/generales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","name":"Re-flexiones\/generales"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","position":2,"name":"Re-flexiones\/generales","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#listItem","name":"Re-flexiones&#8230; 695"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#listItem","position":3,"name":"Re-flexiones&#8230; 695","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/#listItem","name":"Re-flexiones\/generales"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/","name":"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro","description":"\"No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso\" Colin Powell","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2013-08-31T00:00:51+02:00","dateModified":"2013-07-24T19:21:56+02:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro","og:description":"&quot;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&quot; Colin Powell","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/31-08-2013\/re-flexiones-695\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg","og:image:width":355,"og:image:height":522,"article:tag":["re-flexiones\/generales"],"article:published_time":"2013-08-30T23:00:51+00:00","article:modified_time":"2013-07-24T18:21:56+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary_large_image","twitter:site":"@AntonioJAlonso","twitter:title":"Re-flexiones\u2026 695 | Blog de Antonio J. Alonso Sampedro","twitter:description":"&quot;No hay secretos para el \u00e9xito: preparaci\u00f3n, trabajo arduo y aprendizaje del fracaso&quot; Colin Powell","twitter:creator":"@AntonioJAlonso","twitter:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/07\/Colin-Powell.jpg"},"aioseo_meta_data":{"post_id":"5594","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 16:54:27","updated":"2025-06-04 02:55:28","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-1se","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6450,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/03-01-2014\/re-flexiones-803\/","url_meta":{"origin":5594,"position":0},"title":"Re-flexiones&#8230; 803","author":"Antonio J. Alonso Sampedro","date":"03\/01\/2014","format":false,"excerpt":"\"No s\u00e9 cual es la clave del \u00e9xito, pero la clave del fracaso es intentar agradar a todo el mundo\" Bill Cosby","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"Bill Cosby","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2013\/12\/Bill-Cosby-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":20024,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/11-08-2020\/re-flexiones-2-876-exito\/","url_meta":{"origin":5594,"position":1},"title":"Re-flexiones&#8230; 2.876 (\u00e9xito)","author":"Antonio J. Alonso Sampedro","date":"11\/08\/2020","format":false,"excerpt":"\"Si hay un secreto del buen \u00e9xito reside en la capacidad para apreciar el punto de vista del pr\u00f3jimo y ver las cosas desde ese punto de vista as\u00ed como del propio\" Henry Ford","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/07\/Henry-Ford1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7856,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-07-2014\/re-flexiones-978\/","url_meta":{"origin":5594,"position":2},"title":"Re-flexiones&#8230; 978","author":"Antonio J. Alonso Sampedro","date":"27\/07\/2014","format":false,"excerpt":"\"Para tener \u00e9xito hay que tener amigos; pero para mantener mucho \u00e9xito hay que tener muchos amigos\" Frank Sinatra","rel":"","context":"En \u00abRe-flexiones\/generales\u00bb","block_context":{"text":"Re-flexiones\/generales","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-generales\/"},"img":{"alt_text":"Frank Sinatra","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/06\/Frank-Sinatra-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":19994,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/06-08-2020\/re-flexiones-2-871-exito\/","url_meta":{"origin":5594,"position":3},"title":"Re-flexiones&#8230; 2.871 (\u00e9xito)","author":"Antonio J. Alonso Sampedro","date":"06\/08\/2020","format":false,"excerpt":"\"En el mundo com\u00fan de los hechos, los malos no son castigados y los buenos recompensados. El \u00e9xito se lo llevan los fuertes y el fracaso los d\u00e9biles\" Oscar Wilde","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":20027,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/12-08-2020\/re-flexiones-2-877-exito\/","url_meta":{"origin":5594,"position":4},"title":"Re-flexiones&#8230; 2.877 (\u00e9xito)","author":"Antonio J. Alonso Sampedro","date":"12\/08\/2020","format":false,"excerpt":"\"La realidad es que los \u00e9xitos se los llevan los fuertes y el fracaso los d\u00e9biles, y eso es todo\" Oscar Wilde","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2018\/02\/Oscar-Wilde1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19970,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/27-07-2020\/re-flexiones-2-861-exito\/","url_meta":{"origin":5594,"position":5},"title":"Re-flexiones&#8230; 2.861 (\u00e9xito)","author":"Antonio J. Alonso Sampedro","date":"27\/07\/2020","format":false,"excerpt":"\"El \u00e9xito es aprender a ir de fracaso en fracaso sin desesperarse\" Winston Churchill","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2015\/07\/Winston-Churchill1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/5594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=5594"}],"version-history":[{"count":3,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/5594\/revisions"}],"predecessor-version":[{"id":5599,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/5594\/revisions\/5599"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=5594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=5594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=5594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}