{"id":6856,"date":"2014-02-15T00:00:50","date_gmt":"2014-02-14T23:00:50","guid":{"rendered":"http:\/\/www.alonso-businesscoaching.es\/blog\/?p=6856"},"modified":"2019-05-14T18:41:56","modified_gmt":"2019-05-14T16:41:56","slug":"el-manana-siempre-muere","status":"publish","type":"post","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/","title":{"rendered":"El Ma\u00f1ana Siempre Muere"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=DbZ6cZJg0JU\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6860\" data-permalink=\"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/el-manana-nunca-muere\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?fit=1186%2C1600&amp;ssl=1\" data-orig-size=\"1186,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"El ma\u00f1ana nunca muere\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?fit=525%2C708&amp;ssl=1\" class=\"aligncenter wp-image-6860\" src=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?resize=432%2C581\" alt=\"El ma\u00f1ana nunca muere\" width=\"432\" height=\"581\" srcset=\"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?resize=222%2C300&amp;ssl=1 222w, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?zoom=2&amp;resize=432%2C581&amp;ssl=1 864w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a><\/p>\n<p>Todo aquel que haya le\u00eddo <em><a href=\"http:\/\/www.alonso-businesscoaching.es\/blog\/2011\/10\/15\/ser-como-james-bond\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\">Ser como James Bond<\/span><\/a><\/em> conocer\u00e1 de mi declarada admiraci\u00f3n por el incombustible agente secreto de n\u00famero impar e igual al de un cristiano futbolista, este con licencia para\u2026 marcar.<\/p>\n<p><em>El Ma\u00f1ana Nunca Muere<\/em> (1997) fue la d\u00e9cimo octava pel\u00edcula de la exitosa serie de James Bond, esta vez con Pierce Brosnan en el esmoquin del incorregible seductor. Su nombre corresponde al fruto de un error casual en la edici\u00f3n de los t\u00edtulos de cr\u00e9dito pues el original quiso ser <em>El Ma\u00f1ana Nunca Miente<\/em>, es decir, <em>Tomorrow Never Lie<\/em>s que por equivocaci\u00f3n en <em>Tomorrow Never Die<\/em>s se vino a quedar. Miente o muere me valen igual pues sobre ambos t\u00edtulos podemos hablar, de uno bien por contar la realidad y de otro mal por confundir al personal.<\/p>\n<p>En Ciencia Estad\u00edstica se dice que la extensi\u00f3n de la muestra asegura un resultado con mayor fiabilidad. Pues bien, la existencia de las personas se rige por el mismo principio de manera que la situaci\u00f3n de cada cual en su vida es tanto m\u00e1s o menos deudora de su pasado en funci\u00f3n de la extensi\u00f3n que vengamos a contemplar. As\u00ed, un verdadero triunfador (al igual que quien no se considere como tal) seguramente no lo ser\u00e1 por lo acontecido en el \u00faltimo a\u00f1o sino por todo lo ocurrido en su vida de atras. Sin ning\u00fan mecanismo conocido de control y siempre con las debidas excepciones (que, como define la citada Estad\u00edstica, ser\u00e1n las menores), mayoritariamente la vida reparte en el largo tiempo una causal justicia que premia merecimientos y castiga dem\u00e9ritos, ubic\u00e1ndonos all\u00ed donde nuestros pasos nos han llevado a estar. <em>El Ma\u00f1ana Nunca Miente<\/em>.<\/p>\n<p>Por tanto y dado que con seguridad a todos los lectores de esta <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/\" target=\"_blank\" rel=\"noopener noreferrer\">Coach-ti\u00f3n<\/a><\/span> les resta todav\u00eda una buena parte de su vida por aprovechar, ser\u00e1 mejor ahora no mirar atr\u00e1s y construir desde ya un camino para que su ma\u00f1ana pueda mejorar. Entonces y por continuar con el antes mencionado criterio temporal, habr\u00e1 que considerar que cuanto mayor sea el plazo de consecuci\u00f3n el resultado podr\u00e1 aspirar a m\u00e1s, por lo que no es cuesti\u00f3n de gastarlo sin la orientaci\u00f3n que mejor nos pueda encaminar (\u00bfcu\u00e1ntos <em>ma\u00f1anas<\/em> ten\u00edamos en la infancia y cuantos ya han muerto y no volver\u00e1n\u2026?). <em>El Ma\u00f1ana Siempre Muere<\/em>.<\/p>\n<p>Y digo yo: si el ma\u00f1ana nunca miente y siempre muere, \u00bfa qu\u00e9 pel\u00edculas esperas para <em>Ser como James Bond<\/em>? o al menos poderle imitar&#8230;<\/p>\n<p style=\"text-align: right;\"><em><strong>Saludos de Antonio J. Alonso Sampedro<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo aquel que haya le\u00eddo Ser como James Bond conocer\u00e1 de mi declarada admiraci\u00f3n por el incombustible agente secreto de n\u00famero impar e igual al de un cristiano futbolista, este con licencia para\u2026 marcar. El Ma\u00f1ana Nunca Muere (1997) fue la d\u00e9cimo octava pel\u00edcula de la exitosa serie de James Bond, esta vez con Pierce &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;El Ma\u00f1ana Siempre Muere&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[25],"tags":[41],"class_list":["post-6856","post","type-post","status-publish","format-standard","hentry","category-coach-tiones","tag-futuro"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Futuro, James Bond\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio J. Alonso Sampedro\"\/>\n\t<meta name=\"keywords\" content=\"futuro,el ma\u00f1ana siempre muere,ser como james bond,blog personal de alonso business coaching,antonio j. alonso,coaching valencia,coaching ejecutivo,coach-tiones\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta property=\"og:description\" content=\"Futuro, James Bond\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1290516206\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t\t<meta property=\"article:tag\" content=\"futuro\" \/>\n\t\t<meta property=\"article:tag\" content=\"el ma\u00f1ana siempre muere\" \/>\n\t\t<meta property=\"article:tag\" content=\"ser como james bond\" \/>\n\t\t<meta property=\"article:tag\" content=\"blog personal de alonso business coaching\" \/>\n\t\t<meta property=\"article:tag\" content=\"antonio j. alonso\" \/>\n\t\t<meta property=\"article:tag\" content=\"coaching valencia\" \/>\n\t\t<meta property=\"article:tag\" content=\"coaching ejecutivo\" \/>\n\t\t<meta property=\"article:tag\" content=\"coach-tiones\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-14T23:00:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-14T16:41:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Futuro, James Bond\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AntonioJAlonso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#article\",\"name\":\"El Ma\\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro\",\"headline\":\"El Ma\\u00f1ana Siempre Muere\",\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.alonso-businesscoaching.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/El-ma%C3%B1ana-nunca-muere.jpg?fit=1186%2C1600&ssl=1\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#articleImage\",\"width\":1186,\"height\":1600},\"datePublished\":\"2014-02-15T00:00:50+01:00\",\"dateModified\":\"2019-05-14T18:41:56+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#webpage\"},\"articleSection\":\"Coach-tiones, futuro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"name\":\"Coach-tiones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"position\":2,\"name\":\"Coach-tiones\",\"item\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#listItem\",\"name\":\"El Ma\\u00f1ana Siempre Muere\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#listItem\",\"position\":3,\"name\":\"El Ma\\u00f1ana Siempre Muere\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/category\\\/coach-tiones\\\/#listItem\",\"name\":\"Coach-tiones\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/\",\"name\":\"Antonio J. Alonso Sampedro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio J. Alonso Sampedro\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AntonioJAlonsoSampedro\",\"https:\\\/\\\/twitter.com\\\/AntonioJAlonso\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#webpage\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/\",\"name\":\"El Ma\\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro\",\"description\":\"Futuro, James Bond\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/15-02-2014\\\/el-manana-siempre-muere\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/author\\\/antoniojalonso\\\/#author\"},\"datePublished\":\"2014-02-15T00:00:50+01:00\",\"dateModified\":\"2019-05-14T18:41:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/\",\"name\":\"Blog de Antonio J. Alonso Sampedro\",\"alternateName\":\"Blog Antonio J Alonso Sampedro\",\"description\":\"Duda razonable y reflexi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alonso-businesscoaching.es\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro","description":"Futuro, James Bond","canonical_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/","robots":"max-image-preview:large","keywords":"futuro,el ma\u00f1ana siempre muere,ser como james bond,blog personal de alonso business coaching,antonio j. alonso,coaching valencia,coaching ejecutivo,coach-tiones","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#article","name":"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro","headline":"El Ma\u00f1ana Siempre Muere","author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma%C3%B1ana-nunca-muere.jpg?fit=1186%2C1600&ssl=1","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#articleImage","width":1186,"height":1600},"datePublished":"2014-02-15T00:00:50+01:00","dateModified":"2019-05-14T18:41:56+02:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#webpage"},"isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#webpage"},"articleSection":"Coach-tiones, futuro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/www.alonso-businesscoaching.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","name":"Coach-tiones"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","position":2,"name":"Coach-tiones","item":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#listItem","name":"El Ma\u00f1ana Siempre Muere"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#listItem","position":3,"name":"El Ma\u00f1ana Siempre Muere","previousItem":{"@type":"ListItem","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/#listItem","name":"Coach-tiones"}}]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"Person","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/","name":"Antonio J. Alonso Sampedro","image":{"@type":"ImageObject","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/95093c98e30a1cf7c7488db9d1c6571624ebb476bc371ed74265da02b3246157?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio J. Alonso Sampedro"},"sameAs":["https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","https:\/\/twitter.com\/AntonioJAlonso"]},{"@type":"WebPage","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#webpage","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/","name":"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro","description":"Futuro, James Bond","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/#breadcrumblist"},"author":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"creator":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/author\/antoniojalonso\/#author"},"datePublished":"2014-02-15T00:00:50+01:00","dateModified":"2019-05-14T18:41:56+02:00"},{"@type":"WebSite","@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#website","url":"https:\/\/www.alonso-businesscoaching.es\/blog\/","name":"Blog de Antonio J. Alonso Sampedro","alternateName":"Blog Antonio J Alonso Sampedro","description":"Duda razonable y reflexi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.alonso-businesscoaching.es\/blog\/#person"}}]},"og:locale":"es_ES","og:site_name":"Blog de Antonio J. Alonso Sampedro","og:type":"article","og:title":"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro","og:description":"Futuro, James Bond","og:url":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-02-2014\/el-manana-siempre-muere\/","fb:admins":"1290516206","og:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg","og:image:secure_url":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg","og:image:width":1186,"og:image:height":1600,"article:tag":["futuro","el ma\u00f1ana siempre muere","ser como james bond","blog personal de alonso business coaching","antonio j. alonso","coaching valencia","coaching ejecutivo","coach-tiones"],"article:published_time":"2014-02-14T23:00:50+00:00","article:modified_time":"2019-05-14T16:41:56+00:00","article:publisher":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","article:author":"https:\/\/www.facebook.com\/AntonioJAlonsoSampedro","twitter:card":"summary","twitter:site":"@AntonioJAlonso","twitter:title":"El Ma\u00f1ana Siempre Muere | Blog de Antonio J. Alonso Sampedro","twitter:description":"Futuro, James Bond","twitter:creator":"@AntonioJAlonso","twitter:image":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/02\/El-ma\u00f1ana-nunca-muere.jpg"},"aioseo_meta_data":{"post_id":"6856","title":"El Ma\u00f1ana Siempre Muere | #site_title","description":"Futuro, James Bond","keywords":[{"label":"Futuro","value":"Futuro"},{"label":"El ma\u00f1ana siempre muere","value":"El ma\u00f1ana siempre muere"},{"label":"Ser como James Bond","value":"Ser como James Bond"},{"label":"Blog Personal de Alonso BUSINESS COACHING","value":"Blog Personal de Alonso BUSINESS COACHING"},{"label":"Antonio J. Alonso","value":"Antonio J. Alonso"},{"label":"Coaching Valencia","value":"Coaching Valencia"},{"label":"Coaching Ejecutivo","value":"Coaching Ejecutivo"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-03 16:58:01","updated":"2025-06-04 03:15:22","seo_analyzer_scan_date":null},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5YpnT-1MA","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2977,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/15-10-2011\/ser-como-james-bond\/","url_meta":{"origin":6856,"position":0},"title":"Ser como James Bond","author":"Antonio J. Alonso Sampedro","date":"15\/10\/2011","format":false,"excerpt":"Escribir en un Blog de Coaching que trata sobre desarrollo personal y profesional y titular un art\u00edculo como el que encabeza el presente, puede parecer la mejor forma de meterse en un callej\u00f3n sin salida del que no poder escapar sin perder para siempre la credibilidad autoral. A estas alturas\u2026","rel":"","context":"En \u00abCoach-tiones\u00bb","block_context":{"text":"Coach-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/coach-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2011\/10\/Actores-James-Bond.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":21756,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/14-10-2021\/el-fin-de-bond-james-bond\/","url_meta":{"origin":6856,"position":1},"title":"El fin de &#8220;Bond, James Bond&#8221;","author":"Antonio J. Alonso Sampedro","date":"14\/10\/2021","format":false,"excerpt":"No voy a ocultar mi pesar por la p\u00e9rdida de un personaje cinematogr\u00e1fico que me acompa\u00f1a desde la adolescencia y al que he sido fiel hasta ayer, cuando vi... \u201cSin tiempo para morir\u201d, la \u00faltima pel\u00edcula de un James Bond irreconocible en un par de aspectos que son irrenunciables por\u2026","rel":"","context":"En \u00abCine-tiones\u00bb","block_context":{"text":"Cine-tiones","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/cine-tiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/10\/James-Bond-Sin-tiempo-para-morir.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/10\/James-Bond-Sin-tiempo-para-morir.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/10\/James-Bond-Sin-tiempo-para-morir.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/10\/James-Bond-Sin-tiempo-para-morir.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2021\/10\/James-Bond-Sin-tiempo-para-morir.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8485,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/17-10-2014\/marath-tiones-41\/","url_meta":{"origin":6856,"position":2},"title":"MARATH-TIONES&#8230; 41","author":"Antonio J. Alonso Sampedro","date":"17\/10\/2014","format":false,"excerpt":"\u00bfQu\u00e9 tienen en com\u00fan un corredor con un emprendedor\u2026? Pues en mi opini\u00f3n su esp\u00edritu de superaci\u00f3n. Correr sin mejorar puede ser tan frustrante como emprender sin lograr. Llevo muchos a\u00f1os corriendo y algunos menos emprendiendo, pero todos entendiendo que el ma\u00f1ana nunca debe ser peor que el hoy\u2026 39-\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8192,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/18-09-2014\/marath-tiones-16\/","url_meta":{"origin":6856,"position":3},"title":"MARATH-TIONES&#8230; 16","author":"Antonio J. Alonso Sampedro","date":"18\/09\/2014","format":false,"excerpt":"Cuando alguien muere y su cuerpo es enterrado es habitual referirse a que sus restos \u201cdescansan\u201d en tal o cual cementerio, por lo que de ello podemos deducir que la muerte es al descanso lo que la vida al cansancio. En t\u00e9rminos generales y con algunas excepciones justificadas as\u00ed lo\u2026","rel":"","context":"En \u00abMarath-tiones\/diario\u00bb","block_context":{"text":"Marath-tiones\/diario","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-diario\/"},"img":{"alt_text":"Logo Marathon-15","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/10\/Logo-Marathon-15-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22293,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/05-03-2022\/re-flexiones-3-347-suenos\/","url_meta":{"origin":6856,"position":4},"title":"Re-flexiones&#8230; 3.347 (sue\u00f1os)","author":"Antonio J. Alonso Sampedro","date":"05\/03\/2022","format":false,"excerpt":"\"Cuando se muere alguien que nos sue\u00f1a, se muere una parte de nosotros\" Miguel de Unamuno","rel":"","context":"En \u00abRe-flexiones\/tem\u00e1ticas\u00bb","block_context":{"text":"Re-flexiones\/tem\u00e1ticas","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/re-flexiones-tematicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2017\/07\/Miguel-de-Unamuno-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8888,"url":"https:\/\/www.alonso-businesscoaching.es\/blog\/08-11-2014\/hay-que-estar-muerto-para-ser-superior\/","url_meta":{"origin":6856,"position":5},"title":"\u00bfHay que estar muerto para ser superior&#8230;?","author":"Antonio J. Alonso Sampedro","date":"08\/11\/2014","format":false,"excerpt":"Cada primero de Noviembre, en el D\u00eda de Difuntos (Halloween nunca ser\u00e1 para m\u00ed su denominaci\u00f3n), tengo por costumbre escuchar el Don Giovanni (1787) de Mozart para celebrar su excelsa m\u00fasica y que yo estoy vivo mientras que el burlador no. \u00bfQui\u00e9n de los dos es superior\u2026? El libreto de\u2026","rel":"","context":"En \u00abMarath-tiones\/semanal\u00bb","block_context":{"text":"Marath-tiones\/semanal","link":"https:\/\/www.alonso-businesscoaching.es\/blog\/category\/marath-tiones-semanal\/"},"img":{"alt_text":"Don Giovanni","src":"https:\/\/i0.wp.com\/www.alonso-businesscoaching.es\/blog\/wp-content\/uploads\/2014\/11\/Don-Giovanni.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/6856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/comments?post=6856"}],"version-history":[{"count":24,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/6856\/revisions"}],"predecessor-version":[{"id":17975,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/posts\/6856\/revisions\/17975"}],"wp:attachment":[{"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/media?parent=6856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/categories?post=6856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alonso-businesscoaching.es\/blog\/wp-json\/wp\/v2\/tags?post=6856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}